{"id":10371,"date":"2026-07-06T11:30:00","date_gmt":"2026-07-06T14:30:00","guid":{"rendered":"https:\/\/revistaoeste.com\/esporte\/?p=10371"},"modified":"2026-07-06T11:33:56","modified_gmt":"2026-07-06T14:33:56","slug":"belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun","status":"publish","type":"post","link":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/","title":{"rendered":"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o da Fifa sobre Balogun"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A pol\u00eamica envolvendo o atacante Folarin Balogun ganhou um novo cap\u00edtulo \u00e0s v\u00e9speras do confronto entre B\u00e9lgica e Estados Unidos pelas oitavas de final da Copa do Mundo de 2026. A Fifa concedeu \u00e0 Federa\u00e7\u00e3o Belga o direito de recorrer da decis\u00e3o que suspendeu a puni\u00e7\u00e3o aplicada ao atacante norte-americano, liberando o jogador para atuar na partida desta segunda-feira, 6. A informa\u00e7\u00e3o foi divulgada pelo jornal <em>The Athletic<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>+ Leia mais not\u00edcias de&nbsp;<a href=\"https:\/\/revistaoeste.com\/esporte\/\">Oeste Esporte<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Balogun havia sido expulso na vit\u00f3ria dos EUA por 2 a 0 sobre a B\u00f3snia e Herzegovina e, inicialmente, cumpriria suspens\u00e3o autom\u00e1tica de uma partida. No entanto, o Comit\u00ea Disciplinar da Fifa decidiu suspender a execu\u00e7\u00e3o da puni\u00e7\u00e3o por um per\u00edodo probat\u00f3rio de um ano, tornando o atacante novamente eleg\u00edvel para enfrentar a B\u00e9lgica. A decis\u00e3o gerou forte repercuss\u00e3o no futebol internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inconformada, a Federa\u00e7\u00e3o Belga contestou a medida, alegando que a suspens\u00e3o autom\u00e1tica para cart\u00f5es vermelhos est\u00e1 prevista tanto no C\u00f3digo Disciplinar da Fifa quanto no regulamento da Copa do Mundo. Agora, o recurso ser\u00e1 analisado por um membro independente do Comit\u00ea de Apela\u00e7\u00f5es da entidade, que poder\u00e1 manter ou reverter a decis\u00e3o antes da partida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O caso tamb\u00e9m provocou rea\u00e7\u00f5es de outras entidades do futebol. A UEFA criticou duramente a postura da Fifa, classificando a decis\u00e3o como &#8220;sem precedentes&#8221; e afirmando que ela coloca em risco a credibilidade das regras da competi\u00e7\u00e3o. Apesar do recurso aceito, Balogun segue liberado para entrar em campo at\u00e9 que haja uma decis\u00e3o definitiva sobre o caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pol\u00eamica envolvendo o atacante Folarin Balogun ganhou um novo cap\u00edtulo \u00e0s v\u00e9speras do confronto entre B\u00e9lgica e Estados Unidos pelas oitavas&hellip;<\/p>\n","protected":false},"author":5,"featured_media":5326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[110,276,23,75,138,44,29],"class_list":["post-10371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-110","tag-belgica","tag-copa-do-mundo","tag-copa-do-mundo-2026","tag-estados-unidos","tag-fifa","tag-futebol"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B\u00e9lgica consegue direito de recorrer contra decis\u00e3o sobre Balogun<\/title>\n<meta name=\"description\" content=\"Fifa concedeu \u00e0 Federa\u00e7\u00e3o Belga o direito de recorrer da decis\u00e3o que suspendeu a puni\u00e7\u00e3o aplicada ao atacante norte-americano,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o sobre Balogun\" \/>\n<meta property=\"og:description\" content=\"Fifa concedeu \u00e0 Federa\u00e7\u00e3o Belga o direito de recorrer da decis\u00e3o que suspendeu a puni\u00e7\u00e3o aplicada ao atacante norte-americano,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/\" \/>\n<meta property=\"og:site_name\" content=\"Oeste Esporte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/oesterevista\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-06T14:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T14:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/Infantino.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Oeste Esporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:site\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oeste Esporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/\"},\"author\":{\"name\":\"Oeste Esporte\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/6622e4d5d99a35adf0de88128e8d66a9\"},\"headline\":\"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o da Fifa sobre Balogun\",\"datePublished\":\"2026-07-06T14:30:00+00:00\",\"dateModified\":\"2026-07-06T14:33:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/\"},\"wordCount\":290,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Infantino.png\",\"keywords\":[\"2026\",\"B\u00e9lgica\",\"Copa do Mundo\",\"Copa do Mundo 2026\",\"Estados Unidos\",\"FIFA\",\"futebol\"],\"articleSection\":[\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/\",\"name\":\"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o sobre Balogun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Infantino.png\",\"datePublished\":\"2026-07-06T14:30:00+00:00\",\"dateModified\":\"2026-07-06T14:33:56+00:00\",\"description\":\"Fifa concedeu \u00e0 Federa\u00e7\u00e3o Belga o direito de recorrer da decis\u00e3o que suspendeu a puni\u00e7\u00e3o aplicada ao atacante norte-americano,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/#primaryimage\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Infantino.png\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Infantino.png\",\"width\":640,\"height\":360,\"caption\":\"Infantino presidente da Fifa | Foto: Reprodu\u00e7\u00e3o\\\/Fifa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o da Fifa sobre Balogun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"name\":\"Oeste Esporte\",\"description\":\"Copa sem Firula\",\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\",\"name\":\"Oeste Esporte\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"width\":500,\"height\":500,\"caption\":\"Oeste Esporte\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/oesterevista\\\/\",\"https:\\\/\\\/x.com\\\/revistaoeste\",\"https:\\\/\\\/www.youtube.com\\\/@OesteEsporte\",\"https:\\\/\\\/www.instagram.com\\\/revistaoeste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/6622e4d5d99a35adf0de88128e8d66a9\",\"name\":\"Oeste Esporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a2c5501fe5eb922c6c1838ad6a759fe758ecb18b48e36083e67f353c16e08ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a2c5501fe5eb922c6c1838ad6a759fe758ecb18b48e36083e67f353c16e08ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a2c5501fe5eb922c6c1838ad6a759fe758ecb18b48e36083e67f353c16e08ac?s=96&d=mm&r=g\",\"caption\":\"Oeste Esporte\"},\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/author\\\/felipebellirevistaoeste-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o sobre Balogun","description":"Fifa concedeu \u00e0 Federa\u00e7\u00e3o Belga o direito de recorrer da decis\u00e3o que suspendeu a puni\u00e7\u00e3o aplicada ao atacante norte-americano,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/","og_locale":"pt_BR","og_type":"article","og_title":"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o sobre Balogun","og_description":"Fifa concedeu \u00e0 Federa\u00e7\u00e3o Belga o direito de recorrer da decis\u00e3o que suspendeu a puni\u00e7\u00e3o aplicada ao atacante norte-americano,","og_url":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/","og_site_name":"Oeste Esporte","article_publisher":"https:\/\/www.facebook.com\/oesterevista\/","article_published_time":"2026-07-06T14:30:00+00:00","article_modified_time":"2026-07-06T14:33:56+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/Infantino.png","type":"image\/png"}],"author":"Oeste Esporte","twitter_card":"summary_large_image","twitter_creator":"@revistaoeste","twitter_site":"@revistaoeste","twitter_misc":{"Escrito por":"Oeste Esporte","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/#article","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/"},"author":{"name":"Oeste Esporte","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/6622e4d5d99a35adf0de88128e8d66a9"},"headline":"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o da Fifa sobre Balogun","datePublished":"2026-07-06T14:30:00+00:00","dateModified":"2026-07-06T14:33:56+00:00","mainEntityOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/"},"wordCount":290,"commentCount":0,"publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/Infantino.png","keywords":["2026","B\u00e9lgica","Copa do Mundo","Copa do Mundo 2026","Estados Unidos","FIFA","futebol"],"articleSection":["\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/","url":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/","name":"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o sobre Balogun","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/#primaryimage"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/Infantino.png","datePublished":"2026-07-06T14:30:00+00:00","dateModified":"2026-07-06T14:33:56+00:00","description":"Fifa concedeu \u00e0 Federa\u00e7\u00e3o Belga o direito de recorrer da decis\u00e3o que suspendeu a puni\u00e7\u00e3o aplicada ao atacante norte-americano,","breadcrumb":{"@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/#primaryimage","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/Infantino.png","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/Infantino.png","width":640,"height":360,"caption":"Infantino presidente da Fifa | Foto: Reprodu\u00e7\u00e3o\/Fifa"},{"@type":"BreadcrumbList","@id":"https:\/\/revistaoeste.com\/esporte\/belgica-consegue-direito-de-recorrer-contra-decisao-da-fifa-sobre-balogun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/revistaoeste.com\/esporte\/"},{"@type":"ListItem","position":2,"name":"B\u00e9lgica consegue direito de recorrer contra decis\u00e3o da Fifa sobre Balogun"}]},{"@type":"WebSite","@id":"https:\/\/revistaoeste.com\/esporte\/#website","url":"https:\/\/revistaoeste.com\/esporte\/","name":"Oeste Esporte","description":"Copa sem Firula","publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revistaoeste.com\/esporte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/revistaoeste.com\/esporte\/#organization","name":"Oeste Esporte","url":"https:\/\/revistaoeste.com\/esporte\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","width":500,"height":500,"caption":"Oeste Esporte"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oesterevista\/","https:\/\/x.com\/revistaoeste","https:\/\/www.youtube.com\/@OesteEsporte","https:\/\/www.instagram.com\/revistaoeste\/"]},{"@type":"Person","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/6622e4d5d99a35adf0de88128e8d66a9","name":"Oeste Esporte","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8a2c5501fe5eb922c6c1838ad6a759fe758ecb18b48e36083e67f353c16e08ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a2c5501fe5eb922c6c1838ad6a759fe758ecb18b48e36083e67f353c16e08ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a2c5501fe5eb922c6c1838ad6a759fe758ecb18b48e36083e67f353c16e08ac?s=96&d=mm&r=g","caption":"Oeste Esporte"},"url":"https:\/\/revistaoeste.com\/esporte\/author\/felipebellirevistaoeste-com\/"}]}},"_links":{"self":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/10371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/comments?post=10371"}],"version-history":[{"count":2,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/10371\/revisions"}],"predecessor-version":[{"id":10373,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/10371\/revisions\/10373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media\/5326"}],"wp:attachment":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media?parent=10371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/categories?post=10371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/tags?post=10371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}