{"id":13191,"date":"2026-07-28T18:30:05","date_gmt":"2026-07-28T21:30:05","guid":{"rendered":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/"},"modified":"2026-07-28T18:30:05","modified_gmt":"2026-07-28T21:30:05","slug":"o-que-minha-filha-viu-no-estadio-me-assustou","status":"publish","type":"post","link":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/","title":{"rendered":"&#8220;O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU&#8221;"},"content":{"rendered":"<div class=\"yap-description\">\n<p>#futebolbrasileiro #brasileir\u00e3o #bebidasalcoholicas #estadios #esportesemfirula #miltonneves #maracan\u00e3<\/p>\n<p>A pol\u00eamica sobre a venda de bebida alco\u00f3lica nos est\u00e1dios continua dividindo opini\u00f5es. No Maracan\u00e3 pode, no Mineir\u00e3o s\u00f3 at\u00e9 o intervalo. Mas e a seguran\u00e7a das fam\u00edlias? Confira esse desabafo real sobre o que acontece nas arquibancadas.<\/p>\n<p>Acesse a Revista Oeste:<br \/>\n<a href=\"https:\/\/revistaoeste.com\/\">https:\/\/revistaoeste.com\/<\/a><\/p>\n<p>Assine a Oeste<br \/>\n<a  href=\"https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF\"  target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF<\/a><\/p>\n<p>Precisa de ajuda com sua assinatura? entre em contato com a nossa equipe\/<br \/>\nwhatsapp  (11) 96059-8900 ou envie um e-mail para: <a href=\"mailto:contato@revistaoeste.com\">contato@revistaoeste.com<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>#futebolbrasileiro #brasileir\u00e3o #bebidasalcoholicas #estadios #esportesemfirula #miltonneves #maracan\u00e3 A pol\u00eamica sobre a venda de bebida alco\u00f3lica nos est\u00e1dios continua dividindo opini\u00f5es. No Maracan\u00e3&hellip;<\/p>\n","protected":false},"author":3,"featured_media":13192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-13191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU&quot; - Oeste Esporte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU&quot; - Oeste Esporte\" \/>\n<meta property=\"og:description\" content=\"#futebolbrasileiro #brasileir\u00e3o #bebidasalcoholicas #estadios #esportesemfirula #miltonneves #maracan\u00e3 A pol\u00eamica sobre a venda de bebida alco\u00f3lica nos est\u00e1dios continua dividindo opini\u00f5es. No Maracan\u00e3&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/\" \/>\n<meta property=\"og:site_name\" content=\"Oeste Esporte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/oesterevista\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-28T21:30:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oeste Esporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:site\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oeste Esporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/\"},\"author\":{\"name\":\"Oeste Esporte\",\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/b65dd1349325a37fba91ff94e4f8ed30\"},\"headline\":\"&#8220;O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU&#8221;\",\"datePublished\":\"2026-07-28T21:30:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/\"},\"wordCount\":112,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg\",\"articleSection\":[\"V\u00eddeos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/\",\"name\":\"\\\"O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU\\\" - Oeste Esporte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg\",\"datePublished\":\"2026-07-28T21:30:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/o-que-minha-filha-viu-no-estadio-me-assustou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#website\",\"url\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/\",\"name\":\"Oeste Esporte\",\"description\":\"Copa sem Firula\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#organization\",\"name\":\"Oeste Esporte\",\"url\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"width\":500,\"height\":500,\"caption\":\"Oeste Esporte\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/oesterevista\\\/\",\"https:\\\/\\\/x.com\\\/revistaoeste\",\"https:\\\/\\\/www.youtube.com\\\/@OesteEsporte\",\"https:\\\/\\\/www.instagram.com\\\/revistaoeste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/b65dd1349325a37fba91ff94e4f8ed30\",\"name\":\"Oeste Esporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"caption\":\"Oeste Esporte\"},\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/author\\\/lucas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU\" - Oeste Esporte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/","og_locale":"pt_BR","og_type":"article","og_title":"\"O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU\" - Oeste Esporte","og_description":"#futebolbrasileiro #brasileir\u00e3o #bebidasalcoholicas #estadios #esportesemfirula #miltonneves #maracan\u00e3 A pol\u00eamica sobre a venda de bebida alco\u00f3lica nos est\u00e1dios continua dividindo opini\u00f5es. No Maracan\u00e3&hellip;","og_url":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/","og_site_name":"Oeste Esporte","article_publisher":"https:\/\/www.facebook.com\/oesterevista\/","article_published_time":"2026-07-28T21:30:05+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg","type":"image\/jpeg"}],"author":"Oeste Esporte","twitter_card":"summary_large_image","twitter_creator":"@revistaoeste","twitter_site":"@revistaoeste","twitter_misc":{"Escrito por":"Oeste Esporte","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/#article","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/"},"author":{"name":"Oeste Esporte","@id":"https:\/\/www.revistaoeste.com\/esporte\/#\/schema\/person\/b65dd1349325a37fba91ff94e4f8ed30"},"headline":"&#8220;O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU&#8221;","datePublished":"2026-07-28T21:30:05+00:00","mainEntityOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/"},"wordCount":112,"commentCount":0,"publisher":{"@id":"https:\/\/www.revistaoeste.com\/esporte\/#organization"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg","articleSection":["V\u00eddeos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/","url":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/","name":"\"O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU\" - Oeste Esporte","isPartOf":{"@id":"https:\/\/www.revistaoeste.com\/esporte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/#primaryimage"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg","datePublished":"2026-07-28T21:30:05+00:00","breadcrumb":{"@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/#primaryimage","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/07\/o-que-minha-filha-viu-no-estadio-me-assustou-thumbnail.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/revistaoeste.com\/esporte\/o-que-minha-filha-viu-no-estadio-me-assustou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.revistaoeste.com\/esporte\/"},{"@type":"ListItem","position":2,"name":"&#8220;O QUE MINHA FILHA VIU NO EST\u00c1DIO ME ASSUSTOU&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.revistaoeste.com\/esporte\/#website","url":"https:\/\/www.revistaoeste.com\/esporte\/","name":"Oeste Esporte","description":"Copa sem Firula","publisher":{"@id":"https:\/\/www.revistaoeste.com\/esporte\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistaoeste.com\/esporte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.revistaoeste.com\/esporte\/#organization","name":"Oeste Esporte","url":"https:\/\/www.revistaoeste.com\/esporte\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.revistaoeste.com\/esporte\/#\/schema\/logo\/image\/","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","width":500,"height":500,"caption":"Oeste Esporte"},"image":{"@id":"https:\/\/www.revistaoeste.com\/esporte\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oesterevista\/","https:\/\/x.com\/revistaoeste","https:\/\/www.youtube.com\/@OesteEsporte","https:\/\/www.instagram.com\/revistaoeste\/"]},{"@type":"Person","@id":"https:\/\/www.revistaoeste.com\/esporte\/#\/schema\/person\/b65dd1349325a37fba91ff94e4f8ed30","name":"Oeste Esporte","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","caption":"Oeste Esporte"},"url":"https:\/\/revistaoeste.com\/esporte\/author\/lucas\/"}]}},"_links":{"self":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/13191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/comments?post=13191"}],"version-history":[{"count":0,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/13191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media\/13192"}],"wp:attachment":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media?parent=13191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/categories?post=13191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/tags?post=13191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}