{"id":3404,"date":"2026-06-08T11:45:00","date_gmt":"2026-06-08T14:45:00","guid":{"rendered":"https:\/\/revistaoeste.com\/esporte\/?p=3404"},"modified":"2026-06-08T11:45:00","modified_gmt":"2026-06-08T14:45:00","slug":"copa-sem-firula-com-milton-neves-08-06-26","status":"publish","type":"post","link":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/","title":{"rendered":"COPA SEM FIRULA, COM MILTON NEVES | 08\/06\/26"},"content":{"rendered":"<div class=\"yap-description\">\n<p>Muita pol\u00eamica, debate, descontra\u00e7\u00e3o, informa\u00e7\u00e3o de credibilidade e opini\u00e3o no Esporte Sem Firula, com Milton Neves, M\u00e1rio &quot;Alem\u00e3o&quot; Monteiro, Portuga, Let\u00edcia Beppler, Alex M\u00fcller e Alfredo Loebeling.<\/p>\n<p>Acesse:<br \/>\n<a href=\"https:\/\/revistaoeste.com\/esporte\/\">https:\/\/revistaoeste.com\/esporte\/<\/a><\/p>\n<p>Assista ao FAROESTE \u00c0 BRASILEIRA no link abaixo:<br \/>\n<a  href=\"https:\/\/youtube.com\/live\/SXoG8XQDVfU?feature=share\"  target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/youtube.com\/live\/SXoG8XQDVfU?feature=share<\/a><\/p>\n<p>Acesse a Revista Oeste:<br \/>\n<a href=\"https:\/\/revistaoeste.com\/\">https:\/\/revistaoeste.com\/<\/a><\/p>\n<p>Assine a Oeste<br \/>\n<a  href=\"https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF\"  target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF<\/a><\/p>\n<p>Precisa de ajuda com sua assinatura? entre em contato com a nossa equipe\/<br \/>\nwhatsapp  (11) 96059-8900 ou envie um e-mail para: <a href=\"mailto:contato@revistaoeste.com\">contato@revistaoeste.com<\/a><\/p>\n<p>#revistaoeste #oeste #esportesemfirula<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Muita pol\u00eamica, debate, descontra\u00e7\u00e3o, informa\u00e7\u00e3o de credibilidade e opini\u00e3o no Esporte Sem Firula, com Milton Neves, M\u00e1rio &quot;Alem\u00e3o&quot; Monteiro, Portuga, Let\u00edcia Beppler,&hellip;<\/p>\n","protected":false},"author":3,"featured_media":3405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-3404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COPA SEM FIRULA, COM MILTON NEVES | 08\/06\/26 - Oeste Esporte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COPA SEM FIRULA, COM MILTON NEVES | 08\/06\/26 - Oeste Esporte\" \/>\n<meta property=\"og:description\" content=\"Muita pol\u00eamica, debate, descontra\u00e7\u00e3o, informa\u00e7\u00e3o de credibilidade e opini\u00e3o no Esporte Sem Firula, com Milton Neves, M\u00e1rio &quot;Alem\u00e3o&quot; Monteiro, Portuga, Let\u00edcia Beppler,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/\" \/>\n<meta property=\"og:site_name\" content=\"Oeste Esporte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/oesterevista\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-08T14:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oeste Esporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:site\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oeste Esporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/\"},\"author\":{\"name\":\"Oeste Esporte\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/b65dd1349325a37fba91ff94e4f8ed30\"},\"headline\":\"COPA SEM FIRULA, COM MILTON NEVES | 08\\\/06\\\/26\",\"datePublished\":\"2026-06-08T14:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/\"},\"wordCount\":115,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg\",\"articleSection\":[\"V\u00eddeos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/\",\"name\":\"COPA SEM FIRULA, COM MILTON NEVES | 08\\\/06\\\/26 - Oeste Esporte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg\",\"datePublished\":\"2026-06-08T14:45:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/#primaryimage\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/copa-sem-firula-com-milton-neves-08-06-26\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COPA SEM FIRULA, COM MILTON NEVES | 08\\\/06\\\/26\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"name\":\"Oeste Esporte\",\"description\":\"Copa sem Firula\",\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\",\"name\":\"Oeste Esporte\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"width\":500,\"height\":500,\"caption\":\"Oeste Esporte\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/oesterevista\\\/\",\"https:\\\/\\\/x.com\\\/revistaoeste\",\"https:\\\/\\\/www.youtube.com\\\/@OesteEsporte\",\"https:\\\/\\\/www.instagram.com\\\/revistaoeste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/b65dd1349325a37fba91ff94e4f8ed30\",\"name\":\"Oeste Esporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"caption\":\"Oeste Esporte\"},\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/author\\\/lucas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COPA SEM FIRULA, COM MILTON NEVES | 08\/06\/26 - Oeste Esporte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/","og_locale":"pt_BR","og_type":"article","og_title":"COPA SEM FIRULA, COM MILTON NEVES | 08\/06\/26 - Oeste Esporte","og_description":"Muita pol\u00eamica, debate, descontra\u00e7\u00e3o, informa\u00e7\u00e3o de credibilidade e opini\u00e3o no Esporte Sem Firula, com Milton Neves, M\u00e1rio &quot;Alem\u00e3o&quot; Monteiro, Portuga, Let\u00edcia Beppler,&hellip;","og_url":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/","og_site_name":"Oeste Esporte","article_publisher":"https:\/\/www.facebook.com\/oesterevista\/","article_published_time":"2026-06-08T14:45:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg","type":"image\/jpeg"}],"author":"Oeste Esporte","twitter_card":"summary_large_image","twitter_creator":"@revistaoeste","twitter_site":"@revistaoeste","twitter_misc":{"Escrito por":"Oeste Esporte","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/#article","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/"},"author":{"name":"Oeste Esporte","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/b65dd1349325a37fba91ff94e4f8ed30"},"headline":"COPA SEM FIRULA, COM MILTON NEVES | 08\/06\/26","datePublished":"2026-06-08T14:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/"},"wordCount":115,"commentCount":0,"publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg","articleSection":["V\u00eddeos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/","url":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/","name":"COPA SEM FIRULA, COM MILTON NEVES | 08\/06\/26 - Oeste Esporte","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/#primaryimage"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg","datePublished":"2026-06-08T14:45:00+00:00","breadcrumb":{"@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/#primaryimage","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/06\/copa-sem-firula-com-milton-neves-08-06-26-thumbnail.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/revistaoeste.com\/esporte\/copa-sem-firula-com-milton-neves-08-06-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/revistaoeste.com\/esporte\/"},{"@type":"ListItem","position":2,"name":"COPA SEM FIRULA, COM MILTON NEVES | 08\/06\/26"}]},{"@type":"WebSite","@id":"https:\/\/revistaoeste.com\/esporte\/#website","url":"https:\/\/revistaoeste.com\/esporte\/","name":"Oeste Esporte","description":"Copa sem Firula","publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revistaoeste.com\/esporte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/revistaoeste.com\/esporte\/#organization","name":"Oeste Esporte","url":"https:\/\/revistaoeste.com\/esporte\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","width":500,"height":500,"caption":"Oeste Esporte"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oesterevista\/","https:\/\/x.com\/revistaoeste","https:\/\/www.youtube.com\/@OesteEsporte","https:\/\/www.instagram.com\/revistaoeste\/"]},{"@type":"Person","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/b65dd1349325a37fba91ff94e4f8ed30","name":"Oeste Esporte","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","caption":"Oeste Esporte"},"url":"https:\/\/revistaoeste.com\/esporte\/author\/lucas\/"}]}},"_links":{"self":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/3404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/comments?post=3404"}],"version-history":[{"count":1,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/3404\/revisions"}],"predecessor-version":[{"id":3952,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/3404\/revisions\/3952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media\/3405"}],"wp:attachment":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media?parent=3404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/categories?post=3404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/tags?post=3404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}