{"id":853,"date":"2026-05-11T18:30:01","date_gmt":"2026-05-11T21:30:01","guid":{"rendered":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/"},"modified":"2026-05-11T18:30:01","modified_gmt":"2026-05-11T21:30:01","slug":"polemica-de-arbitragem-em-remo-x-palmeiras","status":"publish","type":"post","link":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/","title":{"rendered":"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS"},"content":{"rendered":"<div class=\"yap-description\">\n<p>#palmeiras #remo #brasileirao #esportesemfirula #miltonneves<\/p>\n<p>Acesse a Revista Oeste:<br \/>\n<a href=\"https:\/\/revistaoeste.com\/\">https:\/\/revistaoeste.com\/<\/a><\/p>\n<p>Assine a Oeste<br \/>\n<a  href=\"https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF\"  target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF<\/a><\/p>\n<p>Precisa de ajuda com sua assinatura? entre em contato com a nossa equipe\/<br \/>\nwhatsapp  (11) 96059-8900 ou envie um e-mail para: <a href=\"mailto:contato@revistaoeste.com\">contato@revistaoeste.com<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>#palmeiras #remo #brasileirao #esportesemfirula #miltonneves Acesse a Revista Oeste: https:\/\/revistaoeste.com\/ Assine a Oeste https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF Precisa de ajuda com sua assinatura? entre em&hellip;<\/p>\n","protected":false},"author":3,"featured_media":854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS - Oeste Esporte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS - Oeste Esporte\" \/>\n<meta property=\"og:description\" content=\"#palmeiras #remo #brasileirao #esportesemfirula #miltonneves Acesse a Revista Oeste: https:\/\/revistaoeste.com\/ Assine a Oeste https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF Precisa de ajuda com sua assinatura? entre em&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/\" \/>\n<meta property=\"og:site_name\" content=\"Oeste Esporte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/oesterevista\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T21:30:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/screenshot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oeste Esporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:site\" content=\"@revistaoeste\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oeste Esporte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/\"},\"author\":{\"name\":\"Oeste Esporte\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/b65dd1349325a37fba91ff94e4f8ed30\"},\"headline\":\"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS\",\"datePublished\":\"2026-05-11T21:30:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/\"},\"wordCount\":62,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/polemica-de-arbitragem-em-remo-x-palmeiras-thumbnail.jpg\",\"articleSection\":[\"V\u00eddeos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/\",\"name\":\"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS - Oeste Esporte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/polemica-de-arbitragem-em-remo-x-palmeiras-thumbnail.jpg\",\"datePublished\":\"2026-05-11T21:30:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/polemica-de-arbitragem-em-remo-x-palmeiras-thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/polemica-de-arbitragem-em-remo-x-palmeiras-thumbnail.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/polemica-de-arbitragem-em-remo-x-palmeiras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#website\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"name\":\"Oeste Esporte\",\"description\":\"Copa sem Firula\",\"publisher\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#organization\",\"name\":\"Oeste Esporte\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/avatar.jpg\",\"width\":500,\"height\":500,\"caption\":\"Oeste Esporte\"},\"image\":{\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/oesterevista\\\/\",\"https:\\\/\\\/x.com\\\/revistaoeste\",\"https:\\\/\\\/www.youtube.com\\\/@OesteEsporte\",\"https:\\\/\\\/www.instagram.com\\\/revistaoeste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/#\\\/schema\\\/person\\\/b65dd1349325a37fba91ff94e4f8ed30\",\"name\":\"Oeste Esporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g\",\"caption\":\"Oeste Esporte\"},\"url\":\"https:\\\/\\\/revistaoeste.com\\\/esporte\\\/author\\\/lucas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS - Oeste Esporte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/","og_locale":"pt_BR","og_type":"article","og_title":"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS - Oeste Esporte","og_description":"#palmeiras #remo #brasileirao #esportesemfirula #miltonneves Acesse a Revista Oeste: https:\/\/revistaoeste.com\/ Assine a Oeste https:\/\/br.revistaoeste.com\/assine\/?utm_source=youtube&#038;utm_medium=qrcode&#038;utm_campaign=ESF Precisa de ajuda com sua assinatura? entre em&hellip;","og_url":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/","og_site_name":"Oeste Esporte","article_publisher":"https:\/\/www.facebook.com\/oesterevista\/","article_published_time":"2026-05-11T21:30:01+00:00","og_image":[{"width":1000,"height":746,"url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/screenshot.jpg","type":"image\/jpeg"}],"author":"Oeste Esporte","twitter_card":"summary_large_image","twitter_creator":"@revistaoeste","twitter_site":"@revistaoeste","twitter_misc":{"Escrito por":"Oeste Esporte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/#article","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/"},"author":{"name":"Oeste Esporte","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/b65dd1349325a37fba91ff94e4f8ed30"},"headline":"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS","datePublished":"2026-05-11T21:30:01+00:00","mainEntityOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/"},"wordCount":62,"commentCount":0,"publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/polemica-de-arbitragem-em-remo-x-palmeiras-thumbnail.jpg","articleSection":["V\u00eddeos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/","url":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/","name":"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS - Oeste Esporte","isPartOf":{"@id":"https:\/\/revistaoeste.com\/esporte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/#primaryimage"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/#primaryimage"},"thumbnailUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/polemica-de-arbitragem-em-remo-x-palmeiras-thumbnail.jpg","datePublished":"2026-05-11T21:30:01+00:00","breadcrumb":{"@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/#primaryimage","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/polemica-de-arbitragem-em-remo-x-palmeiras-thumbnail.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/05\/polemica-de-arbitragem-em-remo-x-palmeiras-thumbnail.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/revistaoeste.com\/esporte\/polemica-de-arbitragem-em-remo-x-palmeiras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/revistaoeste.com\/esporte\/"},{"@type":"ListItem","position":2,"name":"POL\u00caMICA DE ARBITRAGEM EM REMO X PALMEIRAS"}]},{"@type":"WebSite","@id":"https:\/\/revistaoeste.com\/esporte\/#website","url":"https:\/\/revistaoeste.com\/esporte\/","name":"Oeste Esporte","description":"Copa sem Firula","publisher":{"@id":"https:\/\/revistaoeste.com\/esporte\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revistaoeste.com\/esporte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/revistaoeste.com\/esporte\/#organization","name":"Oeste Esporte","url":"https:\/\/revistaoeste.com\/esporte\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/","url":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","contentUrl":"https:\/\/revistaoeste.com\/esporte\/wp-content\/uploads\/2026\/03\/avatar.jpg","width":500,"height":500,"caption":"Oeste Esporte"},"image":{"@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oesterevista\/","https:\/\/x.com\/revistaoeste","https:\/\/www.youtube.com\/@OesteEsporte","https:\/\/www.instagram.com\/revistaoeste\/"]},{"@type":"Person","@id":"https:\/\/revistaoeste.com\/esporte\/#\/schema\/person\/b65dd1349325a37fba91ff94e4f8ed30","name":"Oeste Esporte","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac8f81dac0a1f39a558fc6505b41ec07db615768322af858b3dd2988c24e83b9?s=96&d=mm&r=g","caption":"Oeste Esporte"},"url":"https:\/\/revistaoeste.com\/esporte\/author\/lucas\/"}]}},"_links":{"self":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/comments?post=853"}],"version-history":[{"count":0,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/posts\/853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media\/854"}],"wp:attachment":[{"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/media?parent=853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/categories?post=853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaoeste.com\/esporte\/wp-json\/wp\/v2\/tags?post=853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}