{"id":17177,"count":2,"description":"","link":"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/","name":"Pr\u00f3posito","slug":"proposito-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de Pr\u00f3posito - Oeste Geral<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Pr\u00f3posito - Oeste Geral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Oeste Geral\" \/>\n<meta property=\"og:image\" content=\"https:\/\/revistaoeste.com\/oestegeral\/wp-content\/uploads\/2025\/05\/Screenshot_37-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"458\" \/>\n\t<meta property=\"og:image:height\" content=\"219\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Pr\u00f3posito - Oeste Geral","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Pr\u00f3posito - Oeste Geral","og_url":"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/","og_site_name":"Oeste Geral","og_image":[{"width":458,"height":219,"url":"https:\/\/revistaoeste.com\/oestegeral\/wp-content\/uploads\/2025\/05\/Screenshot_37-removebg-preview.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/","url":"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/","name":"Arquivo de Pr\u00f3posito - Oeste Geral","isPartOf":{"@id":"https:\/\/revistaoeste.com\/oestegeral\/#website"},"breadcrumb":{"@id":"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/revistaoeste.com\/oestegeral\/tag\/proposito-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/revistaoeste.com\/oestegeral\/"},{"@type":"ListItem","position":2,"name":"Pr\u00f3posito"}]},{"@type":"WebSite","@id":"https:\/\/revistaoeste.com\/oestegeral\/#website","url":"https:\/\/revistaoeste.com\/oestegeral\/","name":"Revista Oeste - Geral","description":"A Revista Oeste oferece ao p\u00fablico informa\u00e7\u00e3o sobre fatos relevantes na pol\u00edtica, na economia e nos acontecimentos da atualidade, com clareza e objetividade","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/revistaoeste.com\/oestegeral\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/revistaoeste.com\/oestegeral\/wp-json\/wp\/v2\/tags\/17177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaoeste.com\/oestegeral\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/revistaoeste.com\/oestegeral\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/revistaoeste.com\/oestegeral\/wp-json\/wp\/v2\/posts?tags=17177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}